{"id":279419,"date":"2026-04-24T07:24:22","date_gmt":"2026-04-24T07:24:22","guid":{"rendered":"https:\/\/iguality.org\/volunteer-football-coordinator-carlos-on-community-connection-and-the-power-of-sports\/"},"modified":"2026-04-24T07:24:22","modified_gmt":"2026-04-24T07:24:22","slug":"vrijwilligersvoetbalcoordinator-carlos-over-de-band-met-de-gemeenschap-en-de-kracht-van-sport","status":"publish","type":"post","link":"https:\/\/iguality.org\/nl\/volunteer-football-coordinator-carlos-on-community-connection-and-the-power-of-sports\/","title":{"rendered":"Co\u00f6rdinator vrijwilligersvoetbal Carlos over gemeenschap, verbinding en de kracht van sport"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Iguality Voices deelt echte verhalen over geestelijke gezondheid uit onze gemeenschap om stigma's te doorbreken en begrip te kweken. In dit artikel ontmoeten we Carlos Sanchez, onze voetbal co\u00f6rdinator vrijwilliger wiens passie voor sport en verbinding heeft bijgedragen aan talloze voetbalsessies.<\/p>","protected":false},"author":3,"featured_media":279425,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"Volunteer Football Coordinator Carlos on Community, Connection and the power of Sports"},"categories":[143],"tags":[38],"class_list":["post-279419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iguality-voices","tag-atblog"],"acf":{"topic":"","image":null,"content":"","sort":"","last_modified":"","category":[]},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/iguality.org\/nl\/wp-json\/wp\/v2\/posts\/279419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iguality.org\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iguality.org\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iguality.org\/nl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/iguality.org\/nl\/wp-json\/wp\/v2\/comments?post=279419"}],"version-history":[{"count":1,"href":"https:\/\/iguality.org\/nl\/wp-json\/wp\/v2\/posts\/279419\/revisions"}],"predecessor-version":[{"id":279431,"href":"https:\/\/iguality.org\/nl\/wp-json\/wp\/v2\/posts\/279419\/revisions\/279431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iguality.org\/nl\/wp-json\/wp\/v2\/media\/279425"}],"wp:attachment":[{"href":"https:\/\/iguality.org\/nl\/wp-json\/wp\/v2\/media?parent=279419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iguality.org\/nl\/wp-json\/wp\/v2\/categories?post=279419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iguality.org\/nl\/wp-json\/wp\/v2\/tags?post=279419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}