{"id":320,"count":5,"description":"","link":"https:\/\/iguality.org\/es\/category\/iguality-voices\/","name":"Voces Iguality","slug":"voces-de-igualdad","taxonomy":"category","parent":0,"meta":[],"acf":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/iguality.org\/es\/category\/iguality-voices\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iguality.org\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/320\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/iguality.org\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/iguality.org\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/iguality.org\\\/es\\\/category\\\/iguality-voices\\\/#listItem\",\"name\":\"Iguality Voices\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/iguality.org\\\/es\\\/category\\\/iguality-voices\\\/#listItem\",\"position\":2,\"name\":\"Iguality Voices\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/iguality.org\\\/es#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/iguality.org\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/320\\\/#collectionpage\",\"url\":\"https:\\\/\\\/iguality.org\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/320\\\/\",\"name\":\"Iguality Voices - Iguality\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iguality.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iguality.org\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/320\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/iguality.org\\\/es\\\/#organization\",\"name\":\"Iguality Barcelona\",\"description\":\"Making mental health care accessible to all.\",\"url\":\"https:\\\/\\\/iguality.org\\\/es\\\/\",\"email\":\"info@iguality.org\",\"foundingDate\":\"2022-08-22\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":2,\"maxValue\":5},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/iguality.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Logos-wide1.png\",\"@id\":\"https:\\\/\\\/iguality.org\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/320\\\/#organizationLogo\",\"width\":3000,\"height\":1000},\"image\":{\"@id\":\"https:\\\/\\\/iguality.org\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/320\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iguality.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/iguality.org\\\/es\\\/\",\"name\":\"Iguality\",\"alternateName\":\"ASSOCIACI\\u00d3 IGUALITY LAB I COMUNITAT\",\"description\":\"Making mental health care accessible to all.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/iguality.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Iguality Voices - Iguality","description":"","canonical_url":"https:\/\/iguality.org\/es\/category\/iguality-voices\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/iguality.org\/es\/wp-json\/wp\/v2\/categories\/320\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/iguality.org\/es#listItem","position":1,"name":"Home","item":"https:\/\/iguality.org\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/iguality.org\/es\/category\/iguality-voices\/#listItem","name":"Iguality Voices"}},{"@type":"ListItem","@id":"https:\/\/iguality.org\/es\/category\/iguality-voices\/#listItem","position":2,"name":"Iguality Voices","previousItem":{"@type":"ListItem","@id":"https:\/\/iguality.org\/es#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/iguality.org\/es\/wp-json\/wp\/v2\/categories\/320\/#collectionpage","url":"https:\/\/iguality.org\/es\/wp-json\/wp\/v2\/categories\/320\/","name":"Iguality Voices - Iguality","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/iguality.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/iguality.org\/es\/wp-json\/wp\/v2\/categories\/320\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/iguality.org\/es\/#organization","name":"Iguality Barcelona","description":"Making mental health care accessible to all.","url":"https:\/\/iguality.org\/es\/","email":"info@iguality.org","foundingDate":"2022-08-22","numberOfEmployees":{"@type":"QuantitativeValue","minValue":2,"maxValue":5},"logo":{"@type":"ImageObject","url":"https:\/\/iguality.org\/wp-content\/uploads\/2022\/08\/Logos-wide1.png","@id":"https:\/\/iguality.org\/es\/wp-json\/wp\/v2\/categories\/320\/#organizationLogo","width":3000,"height":1000},"image":{"@id":"https:\/\/iguality.org\/es\/wp-json\/wp\/v2\/categories\/320\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/iguality.org\/es\/#website","url":"https:\/\/iguality.org\/es\/","name":"Iguality","alternateName":"ASSOCIACI\u00d3 IGUALITY LAB I COMUNITAT","description":"Making mental health care accessible to all.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/iguality.org\/es\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/iguality.org\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&#x2023;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tIguality Voices\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/iguality.org\/es"},{"label":"Iguality Voices","link":"https:\/\/iguality.org\/es\/category\/iguality-voices\/"}],"_links":{"self":[{"href":"https:\/\/iguality.org\/es\/wp-json\/wp\/v2\/categories\/320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iguality.org\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/iguality.org\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/iguality.org\/es\/wp-json\/wp\/v2\/posts?categories=320"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}